{"id":139,"date":"2014-07-24T17:08:38","date_gmt":"2014-07-24T15:08:38","guid":{"rendered":"http:\/\/blog.zeit.de\/recht-subversiv\/?p=139"},"modified":"2015-12-17T18:26:43","modified_gmt":"2015-12-17T17:26:43","slug":"der-tom-cruise-moment","status":"publish","type":"post","link":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/","title":{"rendered":"Der Tom-Cruise-Moment"},"content":{"rendered":"<p><em>Seit es dieses Blog gibt, war geplant, Kollegen, denen ich viel Inspiration und Motivation verdanke, ebenfalls zu Wort kommen zu lassen. Heute schreibt Bonita Meyersfeld, <a href=\"http:\/\/www.wits.ac.za\/academic\/clm\/law\/about\/staff\/13099\/\">Professorin an der University of Witwatersrand in Johannesburg in S\u00fcdafrika<\/a>. Bonita Meyersfeld forscht und lehrt zu Menschenrechten und gr\u00fcndete die Vereinigung der \u201cLawyers against Abuse\u201d<\/em><\/p>\n<p><!--more--><\/p>\n<p>Als ich den Film <em>Eine Frage der Ehre<\/em> mit Tom Cruise zum ersten Mal sah, war ich eine junge Anw\u00e4ltin. Ich liebte den Film und seine Botschaft: Niemand steht \u00fcber dem Gesetz. Viele Jahre sp\u00e4ter schaute ich ihn wieder an und es beeindruckte mich, wie machtvoll der Film das Verteidigen von Menschenrechten und sozialer Gerechtigkeit bewirbt.<\/p>\n<p>Gegen Ende der Geschichte fokussiert die Kamera Tom Cruise, einen Jung-Anwalt, wie er im Buche steht, \u00fcberspr\u00fchend vor Talent und Leidenschaft. Dem unerm\u00fcdlichen Streben nach Gerechtigkeit verpflichtet, zieht er seine Navy-Uniform an, betritt den Gerichtssaal zum ersten Mal und schaut der Personifizierung des B\u00f6sen ins Gesicht: Jack Nickolson, von dem Cruise dann auch gleich das erhoffte Gest\u00e4ndnis bekommt: \u201eSie haben verdammt noch mal recht, ich habe den Code Red befohlen.\u201c In der allerletzten Sequenz dann schaut Tom Cruise herum in dem nun leeren, von der Sonne gek\u00fcssten Mahagony-get\u00e4felten Gerichtssaal, die Musik hebt an und Cruise verl\u00e4sst das Gericht: Das Gute hatte gegen das B\u00f6se gesiegt, es war der Triumph des Gesetzes \u00fcber alle Ungerechtigkeiten.<\/p>\n<p>Jeder junge Mensch, der das sieht, muss in diesem Moment Anwalt werden wollen. Es ist unm\u00f6glich, nicht von diesem Wunsch erf\u00fcllt zu sein. Nat\u00fcrlich geht es darum, nicht irgendein Anwalt zu werden, sondern ein Anwalt f\u00fcr die Entrechteten, ein Menschenrechtsanwalt. Ein Anwalt, der schon in den ersten Monaten nach seiner Zulassung einen eigentlich unsiegbaren Sieg erringt (und dabei noch atemberaubend gut aussieht). Wir wollen dieser eine Anwalt werden, der den Moment erlebt, an dem er begreift, dass er mal so eben alleine die Welt ver\u00e4ndert hat.<\/p>\n<p>Jeder junge Menschenrechtsanwalt will diesen einen Tom-Cruise-Moment.<\/p>\n<p>Doch gibt es diesen Moment \u00fcberhaupt? Unsere Arbeit f\u00fcr Menschenrechte ist selten, wenn \u00fcberhaupt, auf einen Moment des Sieges ausgerichtet. Vielmehr geht es um das zerm\u00fcrbende, konstante, detaillierte und unerf\u00fcllte sowie banale Sammeln von Beweisen, um das Produzieren von Papierbergen, um herausarbeiten zu k\u00f6nnen, ob wir den Fall gewinnen oder eben die Schlacht verlieren. Es ist eine schwierige Arbeit, bei der wir kaum je die Fr\u00fcchte unserer Anstrengungen sehen \u2013 und wenn wir es tun, dann kann es sein, dass wir vor Gericht gewinnen, aber nur wenige konkrete Ver\u00e4nderungen f\u00fcr das Leben unseres Mandanten erreichen.<\/p>\n<p>Wie also messen wir Erfolg?<\/p>\n<p>Ich hatte k\u00fcrzlich die Ehre, bei einem Treffen von jungen Menschenrechtsanw\u00e4lten dabei zu sein. Eine Anw\u00e4ltin, sie hat erst seit Kurzem einen Jura-Abschluss, erz\u00e4hlte mir \u00fcber ihren Frust mit der Arbeit f\u00fcr Menschenrechte. Sie klagte, dass sie in den sechs Monaten, in denen sie arbeitete, die Probleme ihrer Klienten noch nicht zum Guten wenden konnte.<\/p>\n<p>Ich war verbl\u00fcfft: \u00dcber Jahrhunderte hinweg haben Menschen ihr ganzes Leben lang daran gearbeitet, kleinste Ver\u00e4nderungen zu bewirken. Oft sind sie gestorben, bevor es so weit war. Sklaverei, Apartheid, Kinderrechte, Umweltrechte. Das ganze Spektrum von Rechten, es wurde St\u00fcck f\u00fcr St\u00fcck vorangebracht, wie ein beschwerlicher Stein, angeschoben \u00fcber Generationen hinweg von Hunderten Menschenrechtsanw\u00e4lten. Und hier gab es eine Anw\u00e4ltin, die gro\u00dfe Ver\u00e4nderungen in sechs Monaten erreichen wollte.<\/p>\n<p>Aber sie hatte recht: Wir alle, die auf diesem Gebiet arbeiten, sollten einen w\u00fctenden, ungeduldigen und absoluten Anspruch daran haben, dass wir auch wirklich Wandel erm\u00f6glichen k\u00f6nnen. Wir sollten nicht selbstzufrieden oder auch nur zufrieden mit langsamer Justiz oder langsam erreichter Gerechtigkeit sein. Aber wir sollten uns auch stets daran erinnern, dass wir keine Einzelg\u00e4nger sind: Wir arbeiten in einem Netzwerk von Hunderten von Anw\u00e4lten, \u00fcber Dutzende von Generationen hinweg, die soziale Gerechtigkeit St\u00fcck f\u00fcr St\u00fcck voran gebracht haben \u2013 manchmal, an manchen Stellen.<\/p>\n<p>Diese junge Anw\u00e4ltin zum Beispiel w\u00e4re nie eine geworden, wenn es nicht vor ihr ein paar Feministinnen gegeben h\u00e4tte, die die Rechte von Frauen auch in diesem juristischen Beruf erfochten h\u00e4tten.<\/p>\n<p>Wir arbeiten f\u00fcr Menschenrechte, weil wir wissen wollen, ob wir f\u00fcr jemanden Ver\u00e4nderungen erreichen k\u00f6nnen. Weil wir k\u00e4mpfen gegen Elend und Ungerechtigkeit. Aber wenn wir nur die erzielten Ver\u00e4nderungen als unseren Erfolgsmesswert betrachten, dann glaube ich, w\u00fcrden wir alle unseren Kampf einstellen.<\/p>\n<p>Jeder Anwalt will seinen Tom-Cruise-Moment. Aber eben nicht, um den eigenen Erfolg zu messen. Diesen kann man besser daran festmachen, dass ein Mandant endlich mal die M\u00f6glichkeit hat, seine Geschichte jemandem zu erz\u00e4hlen, der zuh\u00f6rt. Erfolgserlebnisse eines Menschenrechtsanwalts erfolgen auch im Privaten, es geht stets um die, denen wir dienen und es ist die Sicht unserer Mandanten, an der wir uns messen sollten. Menschenrechtsarbeit sollte sich nie um den Anwalt drehen, sondern um die Person, f\u00fcr die wir die ganze Arbeit machen.<\/p>\n<p><em>\u00dcbersetzung aus dem Englischen: Lisa Caspari<\/em><\/p>\n<p><em>Wolfgang Kaleck ist Berliner Rechtsanwalt und Generalsekret\u00e4r des European Center for Constitutional and Human Rights (ECCHR). Kaleck hat sich in den vergangenen Jahren mit Menschenrechtsverletzungen in Argentinien bis Abu Ghraib und Kolumbien bis Philippinen besch\u00e4ftigt; aktuell ist der NSA-Whistleblower Edward Snowden einer seiner Mandanten.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit es dieses Blog gibt, war geplant, Kollegen, denen ich viel Inspiration und Motivation verdanke, ebenfalls zu Wort kommen zu lassen. Heute schreibt Bonita Meyersfeld, Professorin an der University of Witwatersrand in Johannesburg in S\u00fcdafrika. Bonita Meyersfeld forscht und lehrt zu Menschenrechten und gr\u00fcndete die Vereinigung der \u201cLawyers against Abuse\u201d<\/p>\n","protected":false},"author":495,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-139","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Der Tom-Cruise-Moment - Recht subversiv<\/title>\n<meta name=\"description\" content=\"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Tom-Cruise-Moment - Recht subversiv\" \/>\n<meta property=\"og:description\" content=\"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/\" \/>\n<meta property=\"og:site_name\" content=\"Recht subversiv\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-24T15:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-17T17:26:43+00:00\" \/>\n<meta name=\"author\" content=\"Wolfgang Kaleck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zeitonline\" \/>\n<meta name=\"twitter:site\" content=\"@zeitonline\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wolfgang Kaleck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/\",\"url\":\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/\",\"name\":\"Der Tom-Cruise-Moment - Recht subversiv\",\"isPartOf\":{\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/#website\"},\"datePublished\":\"2014-07-24T15:08:38+00:00\",\"dateModified\":\"2015-12-17T17:26:43+00:00\",\"author\":{\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/c09e933ba5a4c0c2a3c1f596858cfe27\"},\"description\":\"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/blog.zeit.de\/recht-subversiv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Tom-Cruise-Moment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/#website\",\"url\":\"https:\/\/blog.zeit.de\/recht-subversiv\/\",\"name\":\"Recht subversiv\",\"description\":\"Aus der Werkstatt eines Anwalts und Menschenrechtlers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.zeit.de\/recht-subversiv\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/c09e933ba5a4c0c2a3c1f596858cfe27\",\"name\":\"Wolfgang Kaleck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/70e1a93ae9e3cae27053181ad7f08215c24e98c5aab278a71d818a2946883252?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/70e1a93ae9e3cae27053181ad7f08215c24e98c5aab278a71d818a2946883252?s=96&d=blank&r=g\",\"caption\":\"Wolfgang Kaleck\"},\"url\":\"https:\/\/blog.zeit.de\/recht-subversiv\/author\/wkaleck\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Tom-Cruise-Moment - Recht subversiv","description":"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/","og_locale":"de_DE","og_type":"article","og_title":"Der Tom-Cruise-Moment - Recht subversiv","og_description":"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.","og_url":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/","og_site_name":"Recht subversiv","article_published_time":"2014-07-24T15:08:38+00:00","article_modified_time":"2015-12-17T17:26:43+00:00","author":"Wolfgang Kaleck","twitter_card":"summary_large_image","twitter_creator":"@zeitonline","twitter_site":"@zeitonline","twitter_misc":{"Geschrieben von":"Wolfgang Kaleck","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/","url":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/","name":"Der Tom-Cruise-Moment - Recht subversiv","isPartOf":{"@id":"https:\/\/blog.zeit.de\/recht-subversiv\/#website"},"datePublished":"2014-07-24T15:08:38+00:00","dateModified":"2015-12-17T17:26:43+00:00","author":{"@id":"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/c09e933ba5a4c0c2a3c1f596858cfe27"},"description":"Die Arbeit eines Menschenrechtsanwalts ist oft zerm\u00fcrbend. Jeder tr\u00e4umt deshalb vom Tom Cruise-Moment.","breadcrumb":{"@id":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zeit.de\/recht-subversiv\/2014\/07\/24\/der-tom-cruise-moment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zeit.de\/recht-subversiv\/"},{"@type":"ListItem","position":2,"name":"Der Tom-Cruise-Moment"}]},{"@type":"WebSite","@id":"https:\/\/blog.zeit.de\/recht-subversiv\/#website","url":"https:\/\/blog.zeit.de\/recht-subversiv\/","name":"Recht subversiv","description":"Aus der Werkstatt eines Anwalts und Menschenrechtlers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zeit.de\/recht-subversiv\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/c09e933ba5a4c0c2a3c1f596858cfe27","name":"Wolfgang Kaleck","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zeit.de\/recht-subversiv\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/70e1a93ae9e3cae27053181ad7f08215c24e98c5aab278a71d818a2946883252?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70e1a93ae9e3cae27053181ad7f08215c24e98c5aab278a71d818a2946883252?s=96&d=blank&r=g","caption":"Wolfgang Kaleck"},"url":"https:\/\/blog.zeit.de\/recht-subversiv\/author\/wkaleck\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/users\/495"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":4,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"predecessor-version":[{"id":734,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/posts\/139\/revisions\/734"}],"wp:attachment":[{"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zeit.de\/recht-subversiv\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}