{"id":634,"date":"2008-08-08T06:58:56","date_gmt":"2008-08-08T05:58:56","guid":{"rendered":"http:\/\/blog.zeit.de\/sex\/?p=634"},"modified":"2008-08-08T06:58:56","modified_gmt":"2008-08-08T05:58:56","slug":"unschuldige-spiele","status":"publish","type":"post","link":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/","title":{"rendered":"Unschuldige Spiele"},"content":{"rendered":"<p>Nicht, dass Sie glauben, werte Leserin, gesch\u00e4tzter Leser, ich w\u00e4re in Zeiten des Nicht-Bloggens unt\u00e4tig. Mais pas du tout!<\/p>\n<p>Ich durchforste, archiviere, mache Gedankennotizen und horte massenhaft Bilder und Kurzmeldungen, die dann irgendwann f\u00fcr Sie, gesch\u00e4tzte Leserin, werter Leser, zur Erbauung gereichen sollen.<\/p>\n<p>Nu, und bei all dem Sammeln kommt einem dann eben manchmal jemand zuvor. Die M\u00e4dels von ShinyShiny haben jetzt eine h\u00fcbsche Bildergalerie mit v\u00f6llig <a href=\"http:\/\/www.shinyshiny.tv\/2008\/07\/galleries\/gallery_the_top.php?pic=1#galtitle\">unschuldig dreinsehenden Sextoys<\/a> zusammengestellt, die sich zum Teil bei mir seit einiger Zeit im Ordner &#8222;Sch\u00f6ner Spielen&#8220; ansammeln.<\/p>\n<p>Das hier, zum Beispiel:<\/p>\n<p><img src='https:\/\/blog.zeit.de\/sex\/files\/2008\/08\/bluemchen.jpg' alt='bluemchen.jpg' \/><\/p>\n<p>Manches davon <a href=\"https:\/\/blog.zeit.de\/sex\/?p=337\">kennen wir schon<\/a>, manches finde ich ein wenig beunruhigend. Ein Hello-Kitty-Vibrator?<\/p>\n<p>Egal. Wo sich die Shinys schon so viel Arbeit angetan haben \u2026<\/p>\n<p>Dass sie allerdings diese beiden vergessen haben!<\/p>\n<p><img src='https:\/\/blog.zeit.de\/sex\/files\/2008\/08\/tpz_group.jpg' alt='tpz_group.jpg' \/><\/p>\n<p>Die &#8222;Tickle Popzzz&#8220; <a href=\"http:\/\/bigteazetoys.com\/content\/view\/60\/139\/\">aus dem gleichen Hause<\/a> wie das mittlerweile ber\u00fchmte Entchen und die oben gezeigten Bl\u00fcmchen.<\/p>\n<p>Und vor allem die <a href=\"https:\/\/www.eva.de\/default.aspx?c=shop&#038;pg=21&#038;n=6&#038;id=7\">Wellness-Brush<\/a>, &#8222;f\u00fcr Kopfmassagen und mehr&#8220;:<\/p>\n<p><img src='https:\/\/blog.zeit.de\/sex\/files\/2008\/08\/wellness_brush_1_3.jpg' alt='wellness_brush_1_3.jpg' \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicht, dass Sie glauben, werte Leserin, gesch\u00e4tzter Leser, ich w\u00e4re in Zeiten des Nicht-Bloggens unt\u00e4tig. Mais pas du tout! Ich durchforste, archiviere, mache Gedankennotizen und horte massenhaft Bilder und Kurzmeldungen, die dann irgendwann f\u00fcr Sie, gesch\u00e4tzte Leserin, werter Leser, zur Erbauung gereichen sollen. Nu, und bei all dem Sammeln kommt einem dann eben manchmal jemand [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[607],"tags":[],"class_list":["post-634","post","type-post","status-publish","format-standard","hentry","category-und-was-zum-spielen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unschuldige Spiele - Das Sex-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unschuldige Spiele - Das Sex-Blog\" \/>\n<meta property=\"og:description\" content=\"Nicht, dass Sie glauben, werte Leserin, gesch\u00e4tzter Leser, ich w\u00e4re in Zeiten des Nicht-Bloggens unt\u00e4tig. Mais pas du tout! Ich durchforste, archiviere, mache Gedankennotizen und horte massenhaft Bilder und Kurzmeldungen, die dann irgendwann f\u00fcr Sie, gesch\u00e4tzte Leserin, werter Leser, zur Erbauung gereichen sollen. Nu, und bei all dem Sammeln kommt einem dann eben manchmal jemand [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/\" \/>\n<meta property=\"og:site_name\" content=\"Das Sex-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2008-08-08T05:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zeit.de\/sex\/files\/2008\/08\/bluemchen.jpg\" \/>\n<meta name=\"author\" content=\"Sigrid Neudecker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sigrid Neudecker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/\",\"url\":\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/\",\"name\":\"Unschuldige Spiele - Das Sex-Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.zeit.de\/sex\/#website\"},\"datePublished\":\"2008-08-08T05:58:56+00:00\",\"dateModified\":\"2008-08-08T05:58:56+00:00\",\"author\":{\"@id\":\"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/df7e3212655103b0406c275b324ef17a\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/blog.zeit.de\/sex\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unschuldige Spiele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.zeit.de\/sex\/#website\",\"url\":\"https:\/\/blog.zeit.de\/sex\/\",\"name\":\"Das Sex-Blog\",\"description\":\"Man muss ja nicht immer reden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.zeit.de\/sex\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/df7e3212655103b0406c275b324ef17a\",\"name\":\"Sigrid Neudecker\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b5aec142fc1d5d03ad62f19fc092c4efc75bc7bc873b90418020a889ad841826?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b5aec142fc1d5d03ad62f19fc092c4efc75bc7bc873b90418020a889ad841826?s=96&d=mm&r=g\",\"caption\":\"Sigrid Neudecker\"},\"url\":\"https:\/\/blog.zeit.de\/sex\/author\/sigrid-neudecker\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unschuldige Spiele - Das Sex-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/","og_locale":"de_DE","og_type":"article","og_title":"Unschuldige Spiele - Das Sex-Blog","og_description":"Nicht, dass Sie glauben, werte Leserin, gesch\u00e4tzter Leser, ich w\u00e4re in Zeiten des Nicht-Bloggens unt\u00e4tig. Mais pas du tout! Ich durchforste, archiviere, mache Gedankennotizen und horte massenhaft Bilder und Kurzmeldungen, die dann irgendwann f\u00fcr Sie, gesch\u00e4tzte Leserin, werter Leser, zur Erbauung gereichen sollen. Nu, und bei all dem Sammeln kommt einem dann eben manchmal jemand [&hellip;]","og_url":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/","og_site_name":"Das Sex-Blog","article_published_time":"2008-08-08T05:58:56+00:00","og_image":[{"url":"https:\/\/blog.zeit.de\/sex\/files\/2008\/08\/bluemchen.jpg"}],"author":"Sigrid Neudecker","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Sigrid Neudecker","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/","url":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/","name":"Unschuldige Spiele - Das Sex-Blog","isPartOf":{"@id":"https:\/\/blog.zeit.de\/sex\/#website"},"datePublished":"2008-08-08T05:58:56+00:00","dateModified":"2008-08-08T05:58:56+00:00","author":{"@id":"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/df7e3212655103b0406c275b324ef17a"},"breadcrumb":{"@id":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zeit.de\/sex\/2008\/08\/08\/unschuldige-spiele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zeit.de\/sex\/"},{"@type":"ListItem","position":2,"name":"Unschuldige Spiele"}]},{"@type":"WebSite","@id":"https:\/\/blog.zeit.de\/sex\/#website","url":"https:\/\/blog.zeit.de\/sex\/","name":"Das Sex-Blog","description":"Man muss ja nicht immer reden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zeit.de\/sex\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/df7e3212655103b0406c275b324ef17a","name":"Sigrid Neudecker","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zeit.de\/sex\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b5aec142fc1d5d03ad62f19fc092c4efc75bc7bc873b90418020a889ad841826?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5aec142fc1d5d03ad62f19fc092c4efc75bc7bc873b90418020a889ad841826?s=96&d=mm&r=g","caption":"Sigrid Neudecker"},"url":"https:\/\/blog.zeit.de\/sex\/author\/sigrid-neudecker\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/posts\/634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/comments?post=634"}],"version-history":[{"count":0,"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/posts\/634\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/media?parent=634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/categories?post=634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zeit.de\/sex\/wp-json\/wp\/v2\/tags?post=634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}