{"id":11469,"date":"2012-11-11T15:00:33","date_gmt":"2012-11-11T14:00:33","guid":{"rendered":"http:\/\/blog.zeit.de\/zeit-der-leser\/?p=11469"},"modified":"2012-11-09T18:30:38","modified_gmt":"2012-11-09T17:30:38","slug":"die-kritzelei-der-woche-28","status":"publish","type":"post","link":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/","title":{"rendered":"Die Kritzelei der Woche"},"content":{"rendered":"<p><a href=\"https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11470\" src=\"https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei.jpg\" alt=\"\" width=\"540\" height=\"208\" srcset=\"https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei.jpg 540w, https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei-300x115.jpg 300w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p>Endlich ruft meine Tochter aus Pennsylvania an. Der Hurrikan hat auch ihren Wohnort betroffen, und ich habe mir gro\u00dfe Sorgen gemacht. Nun erfahre ich, dass Sturm, Regen und Schnee bei ihnen zwar heftig waren, dass die umst\u00fcrzenden B\u00e4ume aber \u00bbnur\u00ab auf die Treppe und zwischen die parkenden Autos gefallen sind. Auch der Strom funktioniert wieder: Sie m\u00fcssen die Sauerstoffversorgung f\u00fcr das Aquarium nicht mehr mit dem Schneebesen erledigen. Auf dem Weg zur Arbeit am Rand von New York, erz\u00e4hlt meine Tochter, sei alles unheimlich dunkel. Ich bin sehr erleichtert und bemerke pl\u00f6tzlich, dass ich beim Telefonieren meine ganze Kalenderseite zerkritzelt habe.<\/p>\n<p><strong>Gabriele Messerschmidt<\/strong>, Leipzig<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Endlich ruft meine Tochter aus Pennsylvania an. Der Hurrikan hat auch ihren Wohnort betroffen, und ich habe mir gro\u00dfe Sorgen gemacht. Nun erfahre ich, dass Sturm, Regen und Schnee bei ihnen zwar heftig waren, dass die umst\u00fcrzenden B\u00e4ume aber \u00bbnur\u00ab auf die Treppe und zwischen die parkenden Autos gefallen sind. Auch der Strom funktioniert wieder: [&hellip;]<\/p>\n","protected":false},"author":265,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1874],"tags":[],"class_list":["post-11469","post","type-post","status-publish","format-standard","hentry","category-kritzelei-der-woche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die Kritzelei der Woche - ZEIT der Leser<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Kritzelei der Woche - ZEIT der Leser\" \/>\n<meta property=\"og:description\" content=\"Endlich ruft meine Tochter aus Pennsylvania an. Der Hurrikan hat auch ihren Wohnort betroffen, und ich habe mir gro\u00dfe Sorgen gemacht. Nun erfahre ich, dass Sturm, Regen und Schnee bei ihnen zwar heftig waren, dass die umst\u00fcrzenden B\u00e4ume aber \u00bbnur\u00ab auf die Treppe und zwischen die parkenden Autos gefallen sind. Auch der Strom funktioniert wieder: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/\" \/>\n<meta property=\"og:site_name\" content=\"ZEIT der Leser\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-11T14:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-09T17:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei.jpg\" \/>\n<meta name=\"author\" content=\"&quot;Zeit der Leser&quot;-Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\"Zeit der Leser\"-Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/\",\"url\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/\",\"name\":\"Die Kritzelei der Woche - ZEIT der Leser\",\"isPartOf\":{\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/#website\"},\"datePublished\":\"2012-11-11T14:00:33+00:00\",\"dateModified\":\"2012-11-09T17:30:38+00:00\",\"author\":{\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/583b14e5ad6368c23af846ecbde9f20f\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Kritzelei der Woche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/#website\",\"url\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/\",\"name\":\"ZEIT der Leser\",\"description\":\"Ein Blog mit Ihren Notizen, Gedichten und Bildern f\u00fcr die gedruckte ZEIT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/583b14e5ad6368c23af846ecbde9f20f\",\"name\":\"\\\"Zeit der Leser\\\"-Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e801a681bd3bbf2345131a815930b48d9f8e0a94de1346b624840dc850f67ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e801a681bd3bbf2345131a815930b48d9f8e0a94de1346b624840dc850f67ad0?s=96&d=mm&r=g\",\"caption\":\"\\\"Zeit der Leser\\\"-Redaktion\"},\"url\":\"https:\/\/blog.zeit.de\/zeit-der-leser\/author\/zeit-der-leser-redaktion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Kritzelei der Woche - ZEIT der Leser","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/","og_locale":"de_DE","og_type":"article","og_title":"Die Kritzelei der Woche - ZEIT der Leser","og_description":"Endlich ruft meine Tochter aus Pennsylvania an. Der Hurrikan hat auch ihren Wohnort betroffen, und ich habe mir gro\u00dfe Sorgen gemacht. Nun erfahre ich, dass Sturm, Regen und Schnee bei ihnen zwar heftig waren, dass die umst\u00fcrzenden B\u00e4ume aber \u00bbnur\u00ab auf die Treppe und zwischen die parkenden Autos gefallen sind. Auch der Strom funktioniert wieder: [&hellip;]","og_url":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/","og_site_name":"ZEIT der Leser","article_published_time":"2012-11-11T14:00:33+00:00","article_modified_time":"2012-11-09T17:30:38+00:00","og_image":[{"url":"https:\/\/blog.zeit.de\/zeit-der-leser\/files\/2012\/11\/s86-kritzelei.jpg"}],"author":"\"Zeit der Leser\"-Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"\"Zeit der Leser\"-Redaktion","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/","url":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/","name":"Die Kritzelei der Woche - ZEIT der Leser","isPartOf":{"@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/#website"},"datePublished":"2012-11-11T14:00:33+00:00","dateModified":"2012-11-09T17:30:38+00:00","author":{"@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/583b14e5ad6368c23af846ecbde9f20f"},"breadcrumb":{"@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/2012\/11\/11\/die-kritzelei-der-woche-28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zeit.de\/zeit-der-leser\/"},{"@type":"ListItem","position":2,"name":"Die Kritzelei der Woche"}]},{"@type":"WebSite","@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/#website","url":"https:\/\/blog.zeit.de\/zeit-der-leser\/","name":"ZEIT der Leser","description":"Ein Blog mit Ihren Notizen, Gedichten und Bildern f\u00fcr die gedruckte ZEIT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zeit.de\/zeit-der-leser\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/583b14e5ad6368c23af846ecbde9f20f","name":"\"Zeit der Leser\"-Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zeit.de\/zeit-der-leser\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e801a681bd3bbf2345131a815930b48d9f8e0a94de1346b624840dc850f67ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e801a681bd3bbf2345131a815930b48d9f8e0a94de1346b624840dc850f67ad0?s=96&d=mm&r=g","caption":"\"Zeit der Leser\"-Redaktion"},"url":"https:\/\/blog.zeit.de\/zeit-der-leser\/author\/zeit-der-leser-redaktion\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/posts\/11469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/comments?post=11469"}],"version-history":[{"count":1,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/posts\/11469\/revisions"}],"predecessor-version":[{"id":11471,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/posts\/11469\/revisions\/11471"}],"wp:attachment":[{"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/media?parent=11469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/categories?post=11469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zeit.de\/zeit-der-leser\/wp-json\/wp\/v2\/tags?post=11469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}